{"id":147537,"date":"2026-05-12T00:03:46","date_gmt":"2026-05-12T00:03:46","guid":{"rendered":"https:\/\/sonnevonmallorca.com\/immobilien\/chalet-luminoso-con-piscina-y-vistas-panoramicas-hasta-el-mar-en-costa-den-blanes-cerca-de-palma\/"},"modified":"2026-05-12T09:22:46","modified_gmt":"2026-05-12T09:22:46","slug":"chalet-luminoso-con-piscina-y-vistas-panoramicas-hasta-el-mar-en-costa-den-blanes-cerca-de-palma","status":"publish","type":"immobilien","link":"https:\/\/sonnevonmallorca.com\/es\/propiedades\/chalet-luminoso-con-piscina-y-vistas-panoramicas-hasta-el-mar-en-costa-den-blanes-cerca-de-palma\/","title":{"rendered":"Chalet luminoso con piscina y vistas panor\u00e1micas hasta el mar en Costa den Blanes cerca de Palma"},"content":{"rendered":"<p>Este luminoso e inundado de luz chalet con piscina y vistas panor\u00e1micas hasta el mar se encuentra en Costa den Blanes, no muy lejos de la capital de la isla Palma, en una parcela de aprox. 770m\u00b2. La superficie habitable de aprox. 230m\u00b2 se distribuye en 2 plantas. En la planta superior se encuentra la sala de estar de planta abierta con amplio sal\u00f3n\/comedor con chimenea y cocina integrada con isla, as\u00ed como un dormitorio y un ba\u00f1o. En la planta inferior hay otro dormitorio con un ba\u00f1o y un estudio (dormitorio\/sala de estar) con otro ba\u00f1o. Tambi\u00e9n hay un peque\u00f1o trastero en este nivel.<br \/>\nEn el exterior, el chalet ofrece una bonita zona de piscina y terrazas soleadas desde donde se puede disfrutar de las vistas panor\u00e1micas y parciales al mar lejano.<br \/>\nLa propiedad est\u00e1 equipada con doble acristalamiento de PVC, aire acondicionado fr\u00edo \/ calor, calefacci\u00f3n por suelo radiante en la planta superior y actualmente calefacci\u00f3n central de gasoil en la planta baja. Este \u00faltimo se est\u00e1 convirtiendo actualmente a una bomba de calor. El chalet tambi\u00e9n dispone de un garaje doble.<br \/>\nSi est\u00e1 interesado, estaremos encantados de proporcionarle informaci\u00f3n detallada sobre el chalet y esperamos recibir su consulta sin compromiso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este luminoso e inundado de luz chalet con piscina y vistas panor\u00e1micas hasta el mar se encuentra en Costa den Blanes, no muy lejos de la capital de la isla Palma, en una parcela de aprox. 770m\u00b2. La superficie habitable de aprox. 230m\u00b2 se distribuye en 2 plantas. En la planta superior se encuentra la [&hellip;]<\/p>\n","protected":false},"featured_media":147833,"template":"","property_price_category":[178],"property_features":[347,360,351,349,350],"property_area":[703],"property_city":[615],"property_category":[503],"property_action_category":[346],"class_list":["post-147537","immobilien","type-immobilien","status-publish","has-post-thumbnail","hentry","property_price_category-1500001-bis-3000000-es","property_features-aire-acondicionado","property_features-chimenea-abierta","property_features-despensa","property_features-parcialmente-amueblado","property_features-piscina","property_area-costa-den-blanes-es-3","property_city-costa-den-blanes-es-2","property_category-villas-casas","property_action_category-a-la-venta"],"_links":{"self":[{"href":"https:\/\/sonnevonmallorca.com\/es\/wp-json\/wp\/v2\/immobilien\/147537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonnevonmallorca.com\/es\/wp-json\/wp\/v2\/immobilien"}],"about":[{"href":"https:\/\/sonnevonmallorca.com\/es\/wp-json\/wp\/v2\/types\/immobilien"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonnevonmallorca.com\/es\/wp-json\/wp\/v2\/media\/147833"}],"wp:attachment":[{"href":"https:\/\/sonnevonmallorca.com\/es\/wp-json\/wp\/v2\/media?parent=147537"}],"wp:term":[{"taxonomy":"property_price_category","embeddable":true,"href":"https:\/\/sonnevonmallorca.com\/es\/wp-json\/wp\/v2\/property_price_category?post=147537"},{"taxonomy":"property_features","embeddable":true,"href":"https:\/\/sonnevonmallorca.com\/es\/wp-json\/wp\/v2\/property_features?post=147537"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/sonnevonmallorca.com\/es\/wp-json\/wp\/v2\/property_area?post=147537"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/sonnevonmallorca.com\/es\/wp-json\/wp\/v2\/property_city?post=147537"},{"taxonomy":"property_category","embeddable":true,"href":"https:\/\/sonnevonmallorca.com\/es\/wp-json\/wp\/v2\/property_category?post=147537"},{"taxonomy":"property_action_category","embeddable":true,"href":"https:\/\/sonnevonmallorca.com\/es\/wp-json\/wp\/v2\/property_action_category?post=147537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}